{"id":5291,"date":"2024-06-26T13:18:59","date_gmt":"2024-06-26T05:18:59","guid":{"rendered":"https:\/\/germanyseppes.com\/?page_id=5291"},"modified":"2024-12-18T09:32:17","modified_gmt":"2024-12-18T01:32:17","slug":"car-industry","status":"publish","type":"page","link":"https:\/\/germanyseppes.com\/es\/car-industry\/","title":{"rendered":"Industria Automotriz"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5291\" class=\"elementor elementor-5291\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34e8de4 ct-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34e8de4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c5fa36\" data-id=\"2c5fa36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e20f17f elementor-widget elementor-widget-heading\" data-id=\"e20f17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aplicaci\u00f3n en la Industria Automotriz<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87e52e9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"87e52e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En los entornos de producci\u00f3n altamente eficientes de las plantas automotrices, las puertas r\u00e1pidas SEPPES, puertas r\u00edgidas de alta velocidad, puertas de protecci\u00f3n de seguridad y puertas r\u00e1pidas apiladoras demuestran un rendimiento y una fiabilidad superiores. Nuestros productos no solo satisfacen las demandas de conmutaci\u00f3n de alta frecuencia, sino que tambi\u00e9n garantizan seguridad y durabilidad, convirti\u00e9ndose en equipos indispensables y esenciales en el proceso moderno de fabricaci\u00f3n automotriz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-14e7731 e-flex e-con-boxed e-con e-parent\" data-id=\"14e7731\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91bb0fb elementor-widget elementor-widget-spacer\" data-id=\"91bb0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac525d1 e-flex e-con-boxed e-con e-parent\" data-id=\"ac525d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb5eab elementor-widget elementor-widget-heading\" data-id=\"cfb5eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industria Automotriz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f4a3a8 elementor-widget elementor-widget-image\" data-id=\"8f4a3a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u6c7d\u8f66.jpg\" class=\"attachment-full size-full wp-image-5293\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u6c7d\u8f66.jpg 800w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u6c7d\u8f66-300x225.jpg 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u6c7d\u8f66-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb63f89 e-flex e-con-boxed e-con e-parent\" data-id=\"cb63f89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e583a83 elementor-widget elementor-widget-spacer\" data-id=\"e583a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6faaea e-grid e-con-boxed e-con e-parent\" data-id=\"a6faaea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1a8e14 elementor-widget elementor-widget-image\" data-id=\"e1a8e14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/72.jpg\" class=\"attachment-full size-full wp-image-5295\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/72.jpg 750w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/72-300x300.jpg 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/72-150x150.jpg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fd3f27 e-grid e-con-full e-con e-child\" data-id=\"7fd3f27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d98a618 elementor-widget elementor-widget-text-editor\" data-id=\"d98a618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Puerta R\u00e1pida de PVC<\/h5><p>Con sus velocidades r\u00e1pidas de apertura y cierre y su eficiente rendimiento de sellado, las puertas r\u00e1pidas son ideales para las l\u00edneas de producci\u00f3n de talleres. Ya sea en un \u00e1rea de producci\u00f3n o en un corredor log\u00edstico, garantizan un flujo de materiales fluido y sin obst\u00e1culos, mejorando la eficiencia productiva.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28ca0f2 elementor-widget elementor-widget-image\" data-id=\"28ca0f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/high-speed-spiral-door-6.jpg\" class=\"attachment-large size-large wp-image-5294\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/high-speed-spiral-door-6.jpg 750w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/high-speed-spiral-door-6-300x300.jpg 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/high-speed-spiral-door-6-150x150.jpg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f358a9f elementor-widget elementor-widget-text-editor\" data-id=\"f358a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Puerta Espiral de Alta Velocidad<\/h5><p>Utilizando materiales de alta resistencia y tecnolog\u00eda avanzada de inhalaci\u00f3n espiral por turbina, las puertas r\u00edgidas de alta velocidad no solo tienen una excelente resistencia al viento y aislamiento t\u00e9rmico, sino que tambi\u00e9n proporcionan una seguridad confiable. Especialmente adecuadas para el exterior del taller, garaje subterr\u00e1neo y otras \u00e1reas que requieren protecci\u00f3n de alta resistencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba0ee8 elementor-widget elementor-widget-text-editor\" data-id=\"cba0ee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Puerta de Protecci\u00f3n de Seguridad<\/h5><p>Dise\u00f1ada para la sala de operaciones de robots y el \u00e1rea de aislamiento de equipos, la puerta de protecci\u00f3n tiene una excelente resistencia al impacto y m\u00faltiples dispositivos de protecci\u00f3n de seguridad para garantizar la seguridad de los operadores y el equipo. Su sistema de control inteligente y altamente sensible puede vincularse con otros equipos para mejorar a\u00fan m\u00e1s la seguridad y automatizaci\u00f3n de la producci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04f356e elementor-widget elementor-widget-image\" data-id=\"04f356e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-8-1-7.jpg\" class=\"attachment-large size-large wp-image-5296\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-8-1-7.jpg 750w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-8-1-7-300x300.jpg 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-8-1-7-150x150.jpg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb13b73 elementor-widget elementor-widget-text-editor\" data-id=\"eb13b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Puerta R\u00e1pida de Apilamiento<\/h5><p>Con su innovador m\u00e9todo de elevaci\u00f3n plegable y dise\u00f1o de palanca resistente al viento, la Puerta R\u00e1pida Apiladora se desempe\u00f1a particularmente bien al tratar con grandes aberturas y entornos de viento fuerte. Su dise\u00f1o modular desmontable facilita y abarata el mantenimiento, convirti\u00e9ndola en la elecci\u00f3n ideal para accesos log\u00edsticos en f\u00e1bricas automotrices.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf77a65 elementor-widget elementor-widget-image\" data-id=\"cf77a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u5806\u79ef-1.jpg\" class=\"attachment-large size-large wp-image-5297\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u5806\u79ef-1.jpg 750w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u5806\u79ef-1-300x300.jpg 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u5806\u79ef-1-150x150.jpg 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca34a43 e-flex e-con-boxed e-con e-parent\" data-id=\"ca34a43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1765f81 elementor-widget elementor-widget-spacer\" data-id=\"1765f81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a98954 e-flex e-con-boxed e-con e-parent\" data-id=\"5a98954\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-066faf5 elementor-widget elementor-widget-heading\" data-id=\"066faf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caso de Cliente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e26496 elementor-arrows-position-outside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"7e26496\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize,to_webp,s_webp\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/Benz-300x300.jpg\" alt=\"Mercedes-Benz.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize,to_webp,s_webp\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/Ford-300x300.jpg\" alt=\"Ford\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize,to_webp,s_webp\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/Volkswagen-1-300x300.jpg\" alt=\"Volkswagen (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u7279\u65af\u62c9-300x300.jpg\" alt=\"Tesla.\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u5b9d\u9a6c-300x300.jpg\" alt=\"BMW.\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61422b7 e-flex e-con-boxed e-con e-parent\" data-id=\"61422b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b04b1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0b04b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70784f7 e-flex e-con-boxed e-con e-parent\" data-id=\"70784f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6d64a00 e-con-full e-flex e-con e-child\" data-id=\"6d64a00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de208f7 elementor-widget elementor-widget-heading\" data-id=\"de208f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Somos un proveedor amigable de empresas Fortune 500<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64dc248 elementor-widget elementor-widget-text-editor\" data-id=\"64dc248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gracias a productos profesionales y reputaci\u00f3n de marca, SEPPES se ha convertido en proveedor colaborador de m\u00e1s de 60 empresas Fortune 500 como IKEA, Tyson, Logitech, Thermo Fisher y AkzoNobel; establece buenas relaciones de cooperaci\u00f3n con redes el\u00e9ctricas; proporciona productos y servicios de soporte para Bosch, Volkswagen, Huawei, Geely, Yangzijiang Pharmaceutical, Hikvision, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1666f4 elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"c1666f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00e1s informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6a5f41 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-image\" data-id=\"a6a5f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"1024\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2023\/03\/company-4-827x1024.webp\" class=\"attachment-large size-large wp-image-1544\" alt=\"empresa seppes\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2023\/03\/company-4-827x1024.webp 827w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2023\/03\/company-4-242x300.webp 242w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2023\/03\/company-4-768x951.webp 768w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2023\/03\/company-4.webp 945w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcd0733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcd0733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76b0460\" data-id=\"76b0460\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5277151 elementor-widget elementor-widget-heading\" data-id=\"5277151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Por qu\u00e9 elegir los equipos de muelle SEPPES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c314a7 elementor-widget elementor-widget-text-editor\" data-id=\"1c314a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dise\u00f1o superior, calidad inquebrantable y una creciente lista de clientes satisfechos han convertido a SEPPES en un pionero en la industria de equipos para muelles. Todos los productos principales cuentan con cerca de 20 certificaciones como CE de la UE, SGS, CMA, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43bca61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43bca61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c2cf6d3\" data-id=\"c2cf6d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e89e3cd elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e89e3cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Confianza de Gran Marca\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tConfianza de Gran Marca\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tComo fabricante profesional de puertas industriales, proveedor colaborador de m\u00e1s de 70 empresas Fortune 500.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1f5ee46\" data-id=\"1f5ee46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-230bffa elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"230bffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Excelente Servicio Postventa\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-rock\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tExcelente Servicio Postventa\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tM\u00e1s de 100 puntos de servicio en todo el mundo, brindando soporte t\u00e9cnico en cualquier momento.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3c1e7e0\" data-id=\"3c1e7e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa21adc elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fa21adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"T\u00e9cnico Profesional\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-life-ring\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tT\u00e9cnico Profesional\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOfrecemos personal profesional y t\u00e9cnico con m\u00e1s de 10 a\u00f1os de experiencia laboral.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-196067b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"196067b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-621cb70\" data-id=\"621cb70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5326c elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1a5326c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\" Precio Competitivo \">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-object-ungroup\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\t Precio Competitivo \t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tContamos con f\u00e1bricas profesionales y 30 patentes de invenci\u00f3n de productos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-546eb65\" data-id=\"546eb65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e848d54 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e848d54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Respuesta R\u00e1pida\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-grin\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tRespuesta R\u00e1pida\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLe proporcionamos servicio en l\u00ednea 7*24 horas: respuesta a preguntas, instalaci\u00f3n, postventa...\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-70d8d19\" data-id=\"70d8d19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd977c8 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"dd977c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Entrega R\u00e1pida\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-paper-plane\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#\" >\n\t\t\t\t\t\t\tEntrega R\u00e1pida\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAdmitimos m\u00faltiples t\u00e9rminos comerciales. El pedido m\u00e1s r\u00e1pido puede recibir la mercanc\u00eda en una semana.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f881d16 e-flex e-con-boxed e-con e-parent\" data-id=\"f881d16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce18c84 elementor-widget elementor-widget-spacer\" data-id=\"ce18c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2383b77 e-flex e-con-boxed e-con e-parent\" data-id=\"2383b77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c054fc6 e-con-full e-flex e-con e-child\" data-id=\"c054fc6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f6bafc elementor-widget elementor-widget-heading\" data-id=\"5f6bafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00daltimas noticias<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af5e51a e-con-full e-flex e-con e-child\" data-id=\"af5e51a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e734eae elementor-widget elementor-widget-text-editor\" data-id=\"e734eae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lea nuestro blog, obtenga conocimientos sobre puertas seccionales, niveladores de muelle, refugios de puerta, puertas r\u00e1pidas, y art\u00edculos sobre nuestros casos de cooperaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-161ae86 e-flex e-con-boxed e-con e-parent\" data-id=\"161ae86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d35ae44 elementor-widget elementor-widget-shortcode\" data-id=\"d35ae44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ct-posts-shortcode\" data-prefix=\"blog\"><div class=\"entries\" data-archive=\"default\" data-layout=\"grid\" data-cards=\"boxed\"><article class=\"entry-card card-content post-9888 post type-post status-publish format-standard has-post-thumbnail hentry category-high-speed-door\" ><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_1\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/germanyseppes.com\/es\/category\/high-speed-door\/\" rel=\"tag\" class=\"ct-term-1\">Puerta R\u00e1pida<\/a><\/li><\/ul><h2 class=\"entry-title\"><a href=\"https:\/\/germanyseppes.com\/es\/high-speed-industrial-doors-2\/\" rel=\"bookmark\">Puertas Industriales de Alta Velocidad: Tipos, Beneficios y Gu\u00eda de Compra<\/a><\/h2><a class=\"ct-media-container boundless-image\" href=\"https:\/\/germanyseppes.com\/es\/high-speed-industrial-doors-2\/\" aria-label=\"Puertas Industriales de Alta Velocidad: Tipos, Beneficios y Gu\u00eda de Compra\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28-768x576.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28-768x576.png 768w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28-300x225.png 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28-1024x768.png 1024w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28-16x12.png 16w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/Codex-\u56fe\u50cf-2026\u5e749\u67082\u65e5-11_47_28.png 1448w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><div class=\"entry-excerpt\"><p>Las puertas industriales de alta velocidad est\u00e1n dise\u00f1adas para aberturas de f\u00e1bricas, almacenes y log\u00edstica que requieren tr\u00e1fico frecuente, ciclos de apertura r\u00e1pidos y un mejor control ambiental. Para la mayor\u00eda de las \u00e1reas interiores de producci\u00f3n y almacenamiento, las puertas enrollables flexibles de alta velocidad son una opci\u00f3n pr\u00e1ctica.\u2026<\/p>\n<\/div><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_2\" ><li class=\"meta-author\" itemprop=\"author\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/Person\"><a class=\"ct-meta-element-author\" href=\"https:\/\/germanyseppes.com\/es\/author\/summer-zhu\/\" title=\"Entradas de Leo Jones\" rel=\"author\" itemprop=\"url\"><span itemprop=\"name\">Leo Jones<\/span><\/a><\/li><li class=\"meta-date\" itemprop=\"datePublished\"><time class=\"ct-meta-element-date\" datetime=\"2026-09-02T00:46:43-03:00\">02\/09\/2026<\/time><\/li><\/ul><\/article><article class=\"entry-card card-content post-9869 post type-post status-publish format-standard has-post-thumbnail hentry category-high-speed-door\" ><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_1\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/germanyseppes.com\/es\/category\/high-speed-door\/\" rel=\"tag\" class=\"ct-term-1\">Puerta R\u00e1pida<\/a><\/li><\/ul><h2 class=\"entry-title\"><a href=\"https:\/\/germanyseppes.com\/es\/high-speed-door-maintenance\/\" rel=\"bookmark\">Mantenimiento de Puertas de Alta Velocidad: Lista de Verificaci\u00f3n y Gu\u00eda de Servicio<\/a><\/h2><a class=\"ct-media-container boundless-image\" href=\"https:\/\/germanyseppes.com\/es\/high-speed-door-maintenance\/\" aria-label=\"Mantenimiento de Puertas de Alta Velocidad: Lista de Verificaci\u00f3n y Gu\u00eda de Servicio\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2-768x576.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2-768x576.png 768w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2-300x225.png 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2-1024x768.png 1024w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2-16x12.png 16w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/09\/441c6200-de9a-4e1e-b156-2a4cdd7e67b2.png 1448w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><div class=\"entry-excerpt\"><p>El mantenimiento de puertas de alta velocidad es esencial para f\u00e1bricas, centros log\u00edsticos, talleres y otros edificios donde las puertas autom\u00e1ticas operan repetidamente durante la jornada laboral. Una puerta puede completar cientos de ciclos de apertura y cierre en una instalaci\u00f3n de alta actividad. Con el tiempo, los sensores\u2026<\/p>\n<\/div><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_2\" ><li class=\"meta-author\" itemprop=\"author\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/Person\"><a class=\"ct-meta-element-author\" href=\"https:\/\/germanyseppes.com\/es\/author\/summer-zhu\/\" title=\"Entradas de Leo Jones\" rel=\"author\" itemprop=\"url\"><span itemprop=\"name\">Leo Jones<\/span><\/a><\/li><li class=\"meta-date\" itemprop=\"datePublished\"><time class=\"ct-meta-element-date\" datetime=\"2026-09-01T02:38:09-03:00\">01\/09\/2026<\/time><\/li><\/ul><\/article><article class=\"entry-card card-content post-9862 post type-post status-publish format-standard has-post-thumbnail hentry category-high-speed-door\" ><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_1\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/germanyseppes.com\/es\/category\/high-speed-door\/\" rel=\"tag\" class=\"ct-term-1\">Puerta R\u00e1pida<\/a><\/li><\/ul><h2 class=\"entry-title\"><a href=\"https:\/\/germanyseppes.com\/es\/high-speed-overhead-door\/\" rel=\"bookmark\">Puerta Industrial de Alta Velocidad: Beneficios, Usos y Gu\u00eda de Compra<\/a><\/h2><a class=\"ct-media-container boundless-image\" href=\"https:\/\/germanyseppes.com\/es\/high-speed-overhead-door\/\" aria-label=\"Puerta de Alta Velocidad: Beneficios, Usos y Gu\u00eda de Compra\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3-768x576.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" srcset=\"https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3-768x576.png 768w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3-300x225.png 300w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3-1024x768.png 1024w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3-16x12.png 16w, https:\/\/germanyseppes.com\/wp-content\/uploads\/2026\/08\/2aa05eac-c654-439f-9fe1-6d62ab2991a3.png 1448w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><div class=\"entry-excerpt\"><p>Una puerta de alta velocidad est\u00e1 dise\u00f1ada para entradas industriales y comerciales donde los veh\u00edculos necesitan ingresar con frecuencia, pero la abertura no debe permanecer expuesta durante per\u00edodos prolongados. En comparaci\u00f3n con una puerta seccional o enrollable convencional, un sistema de alta velocidad puede\u2026<\/p>\n<\/div><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"meta_2\" ><li class=\"meta-author\" itemprop=\"author\" itemscope=\"\" itemtype=\"https:\/\/schema.org\/Person\"><a class=\"ct-meta-element-author\" href=\"https:\/\/germanyseppes.com\/es\/author\/summer-zhu\/\" title=\"Entradas de Leo Jones\" rel=\"author\" itemprop=\"url\"><span itemprop=\"name\">Leo Jones<\/span><\/a><\/li><li class=\"meta-date\" itemprop=\"datePublished\"><time class=\"ct-meta-element-date\" datetime=\"2026-08-31T02:33:28-03:00\">31\/08\/2026<\/time><\/li><\/ul><\/article><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0610fa3 e-flex e-con-boxed e-con e-parent\" data-id=\"0610fa3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-311d1e3 e-flex e-con-boxed e-con e-child\" data-id=\"311d1e3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c6219b e-flex e-con-boxed e-con e-child\" data-id=\"0c6219b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d37882 e-con-full e-flex e-con e-child\" data-id=\"2d37882\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b4e2c1 elementor-widget elementor-widget-heading\" data-id=\"2b4e2c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfTiene una idea de negocio en mente?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08fede1 elementor-widget elementor-widget-text-editor\" data-id=\"08fede1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cont\u00e1ctenos ahora para obtener su plan de personalizaci\u00f3n profesional para muelles log\u00edsticos y f\u00e1bricas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be318f e-con-full e-flex e-con e-child\" data-id=\"5be318f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc37d33 elementor-widget elementor-widget-button\" data-id=\"cc37d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/es\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Comencemos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Car Industry Application In the highly efficient production environments of automotive plants, SEPPES\u00a0 speed doors, rigid speed doors, safety protection doors, and rapid stacking doors demonstrate superior performance and reliability. Our products not only meet the demands of high-frequency switching but also ensure safety and durability, making them indispensable and essential equipment in the modern [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5364,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-5291","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":{"page_title_panel":"","has_hero_section":"disabled","da5b4872f9e8334623972e2d166fd56a":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Inicio"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"e6d535d3e1e37507fc0033d9ef7c98b0":"","hero_alignment1":"CT_CSS_SKIP_RULE","hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","af604582675f2c6b2d61704d7aa0b27c":"","hero_structure":"narrow","ce6f705cef06fac676ecc48a8a6948fd":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"bd6f81ef84ae85f9e69d912b8ee9c623":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"8c4a6d2961d44fcfa49a0dd572b8a506":"","page_structure_type":"default","702871a7ab24e49134d063076717b1f5":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"7922427f56353a5999fd9b23b8da9b06":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"uagb_featured_image_src":{"full":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",750,750,false],"thumbnail":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18-150x150.jpg",150,150,true],"medium":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18-300x300.jpg",300,300,true],"medium_large":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",750,750,false],"large":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",750,750,false],"1536x1536":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",750,750,false],"2048x2048":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",750,750,false],"trp-custom-language-flag":["https:\/\/germanyseppes.com\/wp-content\/uploads\/2024\/06\/\u672a\u6807\u9898-18.jpg",12,12,false]},"uagb_author_info":{"display_name":"Leo jones","author_link":"https:\/\/germanyseppes.com\/es\/author\/summer-zhu\/"},"uagb_comment_info":0,"uagb_excerpt":"Car Industry Application In the highly efficient production environments of automotive plants, SEPPES\u00a0 speed doors, rigid speed doors, safety protection doors, and rapid stacking doors demonstrate superior performance and reliability. Our products not only meet the demands of high-frequency switching but also ensure safety and durability, making them indispensable and essential equipment in the modern&hellip;","_links":{"self":[{"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/pages\/5291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/comments?post=5291"}],"version-history":[{"count":16,"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/pages\/5291\/revisions"}],"predecessor-version":[{"id":6393,"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/pages\/5291\/revisions\/6393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/media\/5364"}],"wp:attachment":[{"href":"https:\/\/germanyseppes.com\/es\/wp-json\/wp\/v2\/media?parent=5291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}